		{"id":25919,"date":"2021-01-25T14:02:35","date_gmt":"2021-01-25T13:02:35","guid":{"rendered":"https:\/\/www.solido.com\/?post_type=product&#038;p=25919"},"modified":"2022-09-20T15:02:12","modified_gmt":"2022-09-20T13:02:12","slug":"s1803503-volkswagen-caddy-mk-1-grey-custom-1982","status":"publish","type":"product","link":"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/","title":{"rendered":"Volkswagen Caddy Mk.1 &#8211; Grey Custom &#8211; 1982"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Vehicle customization is a long-standing practice in the USA. A vehicle as original as the Volkswagen Caddy was predestined to be personalized at all levels. Here is a version that mixes &#8220;low-rider&#8221; and &#8220;German style&#8221;. <a href=\"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/\">[&#8230;]<\/a><\/p>\n","protected":false},"featured_media":25921,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[1181],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Volkswagen Caddy Mk.1 - Grey Custom - 1982 - Solido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Volkswagen Caddy Mk.1 - Grey Custom - 1982 - Solido\" \/>\n<meta property=\"og:description\" content=\"Vehicle customization is a long-standing practice in the USA. A vehicle as original as the Volkswagen Caddy was predestined to be personalized at all levels. Here is a version that mixes &quot;low-rider&quot; and &quot;German style&quot;. [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/\" \/>\n<meta property=\"og:site_name\" content=\"Solido\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-20T13:02:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solido.com\/wp-content\/uploads\/2021\/01\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.solido.com\/en\/#website\",\"url\":\"https:\/\/www.solido.com\/en\/\",\"name\":\"Solido\",\"description\":\"Miniatures automobiles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.solido.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.solido.com\/wp-content\/uploads\/2021\/01\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982-01.jpg\",\"contentUrl\":\"https:\/\/www.solido.com\/wp-content\/uploads\/2021\/01\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982-01.jpg\",\"width\":2500,\"height\":1667,\"caption\":\"Volkswagen Caddy Mk.1 - Grey Custom - 1982\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/#webpage\",\"url\":\"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/\",\"name\":\"Volkswagen Caddy Mk.1 - Grey Custom - 1982 - Solido\",\"isPartOf\":{\"@id\":\"https:\/\/www.solido.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/#primaryimage\"},\"datePublished\":\"2021-01-25T13:02:35+00:00\",\"dateModified\":\"2022-09-20T13:02:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Solido\",\"item\":\"https:\/\/www.solido.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The collection\",\"item\":\"https:\/\/www.solido.com\/en\/the-collection\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1\/18 Collection\",\"item\":\"https:\/\/www.solido.com\/en\/product-category\/118-collection-en\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Volkswagen Caddy Mk.1 &#8211; Grey Custom &#8211; 1982\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Volkswagen Caddy Mk.1 - Grey Custom - 1982 - Solido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/","og_locale":"en_US","og_type":"article","og_title":"Volkswagen Caddy Mk.1 - Grey Custom - 1982 - Solido","og_description":"Vehicle customization is a long-standing practice in the USA. A vehicle as original as the Volkswagen Caddy was predestined to be personalized at all levels. Here is a version that mixes \"low-rider\" and \"German style\". [...]","og_url":"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/","og_site_name":"Solido","article_modified_time":"2022-09-20T13:02:12+00:00","og_image":[{"width":2500,"height":1667,"url":"https:\/\/www.solido.com\/wp-content\/uploads\/2021\/01\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.solido.com\/en\/#website","url":"https:\/\/www.solido.com\/en\/","name":"Solido","description":"Miniatures automobiles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solido.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/#primaryimage","inLanguage":"en-US","url":"https:\/\/www.solido.com\/wp-content\/uploads\/2021\/01\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982-01.jpg","contentUrl":"https:\/\/www.solido.com\/wp-content\/uploads\/2021\/01\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982-01.jpg","width":2500,"height":1667,"caption":"Volkswagen Caddy Mk.1 - Grey Custom - 1982"},{"@type":"WebPage","@id":"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/#webpage","url":"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/","name":"Volkswagen Caddy Mk.1 - Grey Custom - 1982 - Solido","isPartOf":{"@id":"https:\/\/www.solido.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/#primaryimage"},"datePublished":"2021-01-25T13:02:35+00:00","dateModified":"2022-09-20T13:02:12+00:00","breadcrumb":{"@id":"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.solido.com\/en\/la-collection\/s1803503-volkswagen-caddy-mk-1-grey-custom-1982\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Solido","item":"https:\/\/www.solido.com\/en\/"},{"@type":"ListItem","position":2,"name":"The collection","item":"https:\/\/www.solido.com\/en\/the-collection\/"},{"@type":"ListItem","position":3,"name":"1\/18 Collection","item":"https:\/\/www.solido.com\/en\/product-category\/118-collection-en\/"},{"@type":"ListItem","position":4,"name":"Volkswagen Caddy Mk.1 &#8211; Grey Custom &#8211; 1982"}]}]}},"_links":{"self":[{"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/product\/25919"}],"collection":[{"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/comments?post=25919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/media\/25921"}],"wp:attachment":[{"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/media?parent=25919"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/product_cat?post=25919"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/product_tag?post=25919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}