		{"id":29195,"date":"2022-05-24T08:58:42","date_gmt":"2022-05-24T06:58:42","guid":{"rendered":"https:\/\/www.solido.com\/?post_type=product&#038;p=29195"},"modified":"2023-10-24T13:55:02","modified_gmt":"2023-10-24T11:55:02","slug":"s9900101-1st-solido-racer-jean-jean-white-2021","status":"publish","type":"product","link":"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/","title":{"rendered":"1st Solido Racer Jean-Jean &#8211; White &#8211; 2021"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":29197,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[1463],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>1st Solido Racer Jean-Jean - White - 2021 - Solido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1st Solido Racer Jean-Jean - White - 2021 - Solido\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Solido\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-24T11:55:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solido.com\/wp-content\/uploads\/2022\/05\/1st-solido-racer-jean-jean-white-2021-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2362\" \/>\n\t<meta property=\"og:image:height\" content=\"1575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.solido.com\/en\/#website\",\"url\":\"https:\/\/www.solido.com\/en\/\",\"name\":\"Solido\",\"description\":\"Miniatures automobiles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.solido.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.solido.com\/wp-content\/uploads\/2022\/05\/1st-solido-racer-jean-jean-white-2021-01.jpg\",\"contentUrl\":\"https:\/\/www.solido.com\/wp-content\/uploads\/2022\/05\/1st-solido-racer-jean-jean-white-2021-01.jpg\",\"width\":2362,\"height\":1575,\"caption\":\"1st Solido Racer Jean-Jean - White - 2021\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/#webpage\",\"url\":\"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/\",\"name\":\"1st Solido Racer Jean-Jean - White - 2021 - Solido\",\"isPartOf\":{\"@id\":\"https:\/\/www.solido.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/#primaryimage\"},\"datePublished\":\"2022-05-24T06:58:42+00:00\",\"dateModified\":\"2023-10-24T11:55:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Solido\",\"item\":\"https:\/\/www.solido.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The collection\",\"item\":\"https:\/\/www.solido.com\/en\/the-collection\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Unclassified\",\"item\":\"https:\/\/www.solido.com\/en\/product-category\/non-classe-en\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"1st Solido Racer Jean-Jean &#8211; White &#8211; 2021\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1st Solido Racer Jean-Jean - White - 2021 - Solido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/","og_locale":"en_US","og_type":"article","og_title":"1st Solido Racer Jean-Jean - White - 2021 - Solido","og_url":"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/","og_site_name":"Solido","article_modified_time":"2023-10-24T11:55:02+00:00","og_image":[{"width":2362,"height":1575,"url":"https:\/\/www.solido.com\/wp-content\/uploads\/2022\/05\/1st-solido-racer-jean-jean-white-2021-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.solido.com\/en\/#website","url":"https:\/\/www.solido.com\/en\/","name":"Solido","description":"Miniatures automobiles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solido.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/#primaryimage","inLanguage":"en-US","url":"https:\/\/www.solido.com\/wp-content\/uploads\/2022\/05\/1st-solido-racer-jean-jean-white-2021-01.jpg","contentUrl":"https:\/\/www.solido.com\/wp-content\/uploads\/2022\/05\/1st-solido-racer-jean-jean-white-2021-01.jpg","width":2362,"height":1575,"caption":"1st Solido Racer Jean-Jean - White - 2021"},{"@type":"WebPage","@id":"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/#webpage","url":"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/","name":"1st Solido Racer Jean-Jean - White - 2021 - Solido","isPartOf":{"@id":"https:\/\/www.solido.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/#primaryimage"},"datePublished":"2022-05-24T06:58:42+00:00","dateModified":"2023-10-24T11:55:02+00:00","breadcrumb":{"@id":"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.solido.com\/en\/la-collection\/s9900101-1st-solido-racer-jean-jean-white-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Solido","item":"https:\/\/www.solido.com\/en\/"},{"@type":"ListItem","position":2,"name":"The collection","item":"https:\/\/www.solido.com\/en\/the-collection\/"},{"@type":"ListItem","position":3,"name":"Unclassified","item":"https:\/\/www.solido.com\/en\/product-category\/non-classe-en\/"},{"@type":"ListItem","position":4,"name":"1st Solido Racer Jean-Jean &#8211; White &#8211; 2021"}]}]}},"_links":{"self":[{"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/product\/29195"}],"collection":[{"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/comments?post=29195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/media\/29197"}],"wp:attachment":[{"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/media?parent=29195"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/product_cat?post=29195"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/product_tag?post=29195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}