		{"id":34692,"date":"2023-08-22T16:45:57","date_gmt":"2023-08-22T14:45:57","guid":{"rendered":"https:\/\/www.solido.com\/?post_type=product&#038;p=34692"},"modified":"2023-10-23T10:36:28","modified_gmt":"2023-10-23T08:36:28","slug":"s4313302-audi-s8-d3-2010","status":"publish","type":"product","link":"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/","title":{"rendered":"Audi S8 (D3) &#8211; 2010"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":34694,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[1183],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Audi S8 (D3) - 2010 - Solido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Audi S8 (D3) - 2010 - Solido\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/\" \/>\n<meta property=\"og:site_name\" content=\"Solido\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-23T08:36:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solido.com\/wp-content\/uploads\/2023\/08\/1-43-audi-s8-d3-white-2010-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.solido.com\/en\/#website\",\"url\":\"https:\/\/www.solido.com\/en\/\",\"name\":\"Solido\",\"description\":\"Miniatures automobiles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.solido.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.solido.com\/wp-content\/uploads\/2023\/08\/1-43-audi-s8-d3-white-2010-01.jpg\",\"contentUrl\":\"https:\/\/www.solido.com\/wp-content\/uploads\/2023\/08\/1-43-audi-s8-d3-white-2010-01.jpg\",\"width\":2500,\"height\":1667,\"caption\":\"Audi S8 (D3) - 2010\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/#webpage\",\"url\":\"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/\",\"name\":\"Audi S8 (D3) - 2010 - Solido\",\"isPartOf\":{\"@id\":\"https:\/\/www.solido.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/#primaryimage\"},\"datePublished\":\"2023-08-22T14:45:57+00:00\",\"dateModified\":\"2023-10-23T08:36:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Solido\",\"item\":\"https:\/\/www.solido.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The collection\",\"item\":\"https:\/\/www.solido.com\/en\/the-collection\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1\/43 Collection\",\"item\":\"https:\/\/www.solido.com\/en\/product-category\/143-collection-en\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Audi S8 (D3) &#8211; 2010\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Audi S8 (D3) - 2010 - Solido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/","og_locale":"en_US","og_type":"article","og_title":"Audi S8 (D3) - 2010 - Solido","og_url":"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/","og_site_name":"Solido","article_modified_time":"2023-10-23T08:36:28+00:00","og_image":[{"width":2500,"height":1667,"url":"https:\/\/www.solido.com\/wp-content\/uploads\/2023\/08\/1-43-audi-s8-d3-white-2010-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.solido.com\/en\/#website","url":"https:\/\/www.solido.com\/en\/","name":"Solido","description":"Miniatures automobiles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solido.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/#primaryimage","inLanguage":"en-US","url":"https:\/\/www.solido.com\/wp-content\/uploads\/2023\/08\/1-43-audi-s8-d3-white-2010-01.jpg","contentUrl":"https:\/\/www.solido.com\/wp-content\/uploads\/2023\/08\/1-43-audi-s8-d3-white-2010-01.jpg","width":2500,"height":1667,"caption":"Audi S8 (D3) - 2010"},{"@type":"WebPage","@id":"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/#webpage","url":"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/","name":"Audi S8 (D3) - 2010 - Solido","isPartOf":{"@id":"https:\/\/www.solido.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/#primaryimage"},"datePublished":"2023-08-22T14:45:57+00:00","dateModified":"2023-10-23T08:36:28+00:00","breadcrumb":{"@id":"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.solido.com\/en\/la-collection\/s4313302-audi-s8-d3-2010\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Solido","item":"https:\/\/www.solido.com\/en\/"},{"@type":"ListItem","position":2,"name":"The collection","item":"https:\/\/www.solido.com\/en\/the-collection\/"},{"@type":"ListItem","position":3,"name":"1\/43 Collection","item":"https:\/\/www.solido.com\/en\/product-category\/143-collection-en\/"},{"@type":"ListItem","position":4,"name":"Audi S8 (D3) &#8211; 2010"}]}]}},"_links":{"self":[{"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/product\/34692"}],"collection":[{"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/comments?post=34692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/media\/34694"}],"wp:attachment":[{"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/media?parent=34692"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/product_cat?post=34692"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.solido.com\/en\/wp-json\/wp\/v2\/product_tag?post=34692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}